{"id":14142,"date":"2025-02-24T12:25:36","date_gmt":"2025-02-24T17:25:36","guid":{"rendered":"https:\/\/www.disneyonice.com\/?page_id=14142"},"modified":"2025-02-25T08:22:23","modified_gmt":"2025-02-25T13:22:23","slug":"cast","status":"publish","type":"page","link":"https:\/\/www.disneyonice.com\/en-id\/princesses-heros\/cast\/","title":{"rendered":"Cast"},"content":{"rendered":"<div class=\"full\" id=\"block_7767833512956e52f77d9f1b53bf4d68\">\n\t<section class=\"felds-block felds-banner-block banner-small pos-left pos-middle\" style=\"background-color:#000000;\">\n\t\t<div class=\"info align-left below-title\" style=\"width: 45%;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"bg-images\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"desktop\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2025\/02\/meet-the-cast-background-desktop-heros.jpg\" alt=\"<em>Disney On Ice<\/em>\" width=\"1920\" height=\"1080\" fetchpriority=\"high\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" class=\"mobile\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2025\/02\/251428950-D33-INTL-Belgium-Logo_Design_FRENCH_Stacked.png\" alt=\"<em>Disney On Ice<\/em>\" width=\"750\" height=\"1334\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/section>\n\t<\/div>\n\n\n\n\n<div class=\"container\">\n\t<section id=\"\" class=\"felds-block felds-cast-block\">\n\t\t<div class=\"block-title\">\n\t\t\tPrincipal Skaters\t\t<\/div>\n\t\t<div class=\"block-content\">\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Behr_Sari_2017_0-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Behr_Sari_2017_0-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Behr_Sari_2017_0-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Behr_Sari_2017_0-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Behr_Sari_2017_0-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Behr_Sari_2017_0-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Behr_Sari_2017_0-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Behr_Sari_2017_0-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/us.png\" alt=\"United States\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tSari Behr\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited States\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/DeLuca_Madison_2015-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/DeLuca_Madison_2015-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/DeLuca_Madison_2015-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/DeLuca_Madison_2015-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/DeLuca_Madison_2015-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/DeLuca_Madison_2015-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/DeLuca_Madison_2015-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/DeLuca_Madison_2015-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/us.png\" alt=\"United States\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tMadison DeLuca\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited States\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1000\" height=\"1250\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Godorozha_Yakiv_2022.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Godorozha_Yakiv_2022.jpg 1000w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Godorozha_Yakiv_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Godorozha_Yakiv_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Godorozha_Yakiv_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Godorozha_Yakiv_2022-51x64.jpg 51w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/ua.png\" alt=\"Ukraine\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tYakiv Godorozha\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUkraine\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Koreline_Denis_2019-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Koreline_Denis_2019-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Koreline_Denis_2019-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Koreline_Denis_2019-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Koreline_Denis_2019-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Koreline_Denis_2019-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Koreline_Denis_2019-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Koreline_Denis_2019-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/ee.png\" alt=\"Estonia\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tDenis Koreline\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tEstonia\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1000\" height=\"1250\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Lourenco_Quentin_2022.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Lourenco_Quentin_2022.jpg 1000w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Lourenco_Quentin_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Lourenco_Quentin_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Lourenco_Quentin_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Lourenco_Quentin_2022-51x64.jpg 51w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/fr.png\" alt=\"France\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tQuentin Lourenco-Aubry\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tFrance\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Martikainen_Piamaria_2022-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Martikainen_Piamaria_2022-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Martikainen_Piamaria_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Martikainen_Piamaria_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Martikainen_Piamaria_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Martikainen_Piamaria_2022-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Martikainen_Piamaria_2022-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Martikainen_Piamaria_2022-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/fi.png\" alt=\"Finland\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tPiamaria Martikainen\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tFinland\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2009\" height=\"2511\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Muhhin_Sergei_2018.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Muhhin_Sergei_2018.jpg 2009w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Muhhin_Sergei_2018-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Muhhin_Sergei_2018-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Muhhin_Sergei_2018-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Muhhin_Sergei_2018-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Muhhin_Sergei_2018-1639x2048.jpg 1639w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Muhhin_Sergei_2018-51x64.jpg 51w\" sizes=\"(max-width: 2009px) 100vw, 2009px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/ee.png\" alt=\"Estonia\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tSergei Muhhin\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tEstonia\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1000\" height=\"1250\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Santee_Sarah_2022.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Santee_Sarah_2022.jpg 1000w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Santee_Sarah_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Santee_Sarah_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Santee_Sarah_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Santee_Sarah_2022-51x64.jpg 51w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/us.png\" alt=\"United States\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tSarah Santee\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited States\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1000\" height=\"1250\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Sjolin_Ida_2022.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Sjolin_Ida_2022.jpg 1000w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Sjolin_Ida_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Sjolin_Ida_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Sjolin_Ida_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Sjolin_Ida_2022-51x64.jpg 51w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/se.png\" alt=\"Sweden\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tIda Sj\u00f6lin\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tSweden\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Storrier_Myles_2022-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Storrier_Myles_2022-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Storrier_Myles_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Storrier_Myles_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Storrier_Myles_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Storrier_Myles_2022-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Storrier_Myles_2022-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/Storrier_Myles_2022-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/gb.png\" alt=\"United Kingdom\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tMyles Storrier\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited Kingdom\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/section>\n<\/div>\n\n\n\n\n<div class=\"container\">\n\t<section id=\"\" class=\"felds-block felds-cast-block\">\n\t\t<div class=\"block-title\">\n\t\t\tCast\t\t<\/div>\n\t\t<div class=\"block-content\">\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1000\" height=\"1250\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Arredondo_Jaime_2022_0.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Arredondo_Jaime_2022_0.jpg 1000w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Arredondo_Jaime_2022_0-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Arredondo_Jaime_2022_0-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Arredondo_Jaime_2022_0-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Arredondo_Jaime_2022_0-51x64.jpg 51w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/mx.png\" alt=\"Mexico\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tNorman Arredondo\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tMexico\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Balanean_Laura_2022-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Balanean_Laura_2022-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Balanean_Laura_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Balanean_Laura_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Balanean_Laura_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Balanean_Laura_2022-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Balanean_Laura_2022-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Balanean_Laura_2022-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/be.png\" alt=\"Belgium\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tLaura Balanean\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tBelgium\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1000\" height=\"1250\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Bartram_Mike_2022.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Bartram_Mike_2022.jpg 1000w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Bartram_Mike_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Bartram_Mike_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Bartram_Mike_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Bartram_Mike_2022-51x64.jpg 51w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/gb.png\" alt=\"United Kingdom\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tMichael Bartram\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited Kingdom\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/12\/Berchova_Lumir_2017-scaled.jpg\" class=\"attachment-full size-full\" alt=\"Lumir Berchova\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/12\/Berchova_Lumir_2017-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/12\/Berchova_Lumir_2017-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/12\/Berchova_Lumir_2017-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/12\/Berchova_Lumir_2017-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/12\/Berchova_Lumir_2017-1600x2000.jpg 1600w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/12\/Berchova_Lumir_2017-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/12\/Berchova_Lumir_2017-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/12\/Berchova_Lumir_2017-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/us.png\" alt=\"United States\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tLumir Bercha\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited States\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2010\" height=\"2513\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Bergerson_Cale_2017.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Bergerson_Cale_2017.jpg 2010w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Bergerson_Cale_2017-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Bergerson_Cale_2017-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Bergerson_Cale_2017-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Bergerson_Cale_2017-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Bergerson_Cale_2017-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Bergerson_Cale_2017-51x64.jpg 51w\" sizes=\"(max-width: 2010px) 100vw, 2010px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/us.png\" alt=\"United States\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tCale Bergerson\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited States\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1000\" height=\"1250\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Brooks_Nadiri_2022_0.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Brooks_Nadiri_2022_0.jpg 1000w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Brooks_Nadiri_2022_0-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Brooks_Nadiri_2022_0-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Brooks_Nadiri_2022_0-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Brooks_Nadiri_2022_0-51x64.jpg 51w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/us.png\" alt=\"United States\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tNadiri Brooks\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited States\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1000\" height=\"1250\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Burger_Bryan_2022.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Burger_Bryan_2022.jpg 1000w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Burger_Bryan_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Burger_Bryan_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Burger_Bryan_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Burger_Bryan_2022-51x64.jpg 51w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/fr.png\" alt=\"France\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tBryan Burger\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tFrance\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1000\" height=\"1250\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Butkute_Goda_2022_0.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Butkute_Goda_2022_0.jpg 1000w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Butkute_Goda_2022_0-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Butkute_Goda_2022_0-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Butkute_Goda_2022_0-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Butkute_Goda_2022_0-51x64.jpg 51w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/lt.png\" alt=\"Lithuania\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tGoda Butkute\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tLithuania\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/10\/Callahan_Hannah_2022-scaled.jpg\" class=\"attachment-full size-full\" alt=\"Hannah Callahan\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/10\/Callahan_Hannah_2022-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/10\/Callahan_Hannah_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/10\/Callahan_Hannah_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/10\/Callahan_Hannah_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/10\/Callahan_Hannah_2022-1600x2000.jpg 1600w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/10\/Callahan_Hannah_2022-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/10\/Callahan_Hannah_2022-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/10\/Callahan_Hannah_2022-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/us.png\" alt=\"United States\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tHannah Callahan\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited States\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Caron_Kamille_2023-scaled.jpg\" class=\"attachment-full size-full\" alt=\"Kamille Caron\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Caron_Kamille_2023-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Caron_Kamille_2023-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Caron_Kamille_2023-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Caron_Kamille_2023-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Caron_Kamille_2023-1600x2000.jpg 1600w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Caron_Kamille_2023-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Caron_Kamille_2023-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Caron_Kamille_2023-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/ca.png\" alt=\"Canada\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tKamille Caron\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tCanada\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1753\" height=\"1739\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png\" class=\"attachment-full size-full\" alt=\"Graphic of an ice skate\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png 1753w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-300x298.png 300w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1024x1016.png 1024w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-150x150.png 150w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-768x762.png 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1536x1524.png 1536w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-64x64.png 64w\" sizes=\"(max-width: 1753px) 100vw, 1753px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/gb.png\" alt=\"United Kingdom\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tRoxanne Collins\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited Kingdom\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Cooper_Nila_2023-scaled.jpg\" class=\"attachment-full size-full\" alt=\"Nila Cooper\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Cooper_Nila_2023-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Cooper_Nila_2023-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Cooper_Nila_2023-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Cooper_Nila_2023-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Cooper_Nila_2023-1600x2000.jpg 1600w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Cooper_Nila_2023-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Cooper_Nila_2023-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Cooper_Nila_2023-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/us.png\" alt=\"United States\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tNila Cooper\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited States\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1000\" height=\"1250\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Fahlander_Andrea_2022.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Fahlander_Andrea_2022.jpg 1000w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Fahlander_Andrea_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Fahlander_Andrea_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Fahlander_Andrea_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Fahlander_Andrea_2022-51x64.jpg 51w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/se.png\" alt=\"Sweden\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tAndrea Fahlander\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tSweden\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Felker_Terese_2023-scaled.jpg\" class=\"attachment-full size-full\" alt=\"Terese Felker\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Felker_Terese_2023-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Felker_Terese_2023-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Felker_Terese_2023-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Felker_Terese_2023-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Felker_Terese_2023-1600x2000.jpg 1600w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Felker_Terese_2023-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Felker_Terese_2023-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Felker_Terese_2023-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/us.png\" alt=\"United States\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tTerese Felker\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited States\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1000\" height=\"1250\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Fish_Matt_2022.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Fish_Matt_2022.jpg 1000w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Fish_Matt_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Fish_Matt_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Fish_Matt_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Fish_Matt_2022-51x64.jpg 51w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/gb.png\" alt=\"United Kingdom\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tMatthew Fish\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited Kingdom\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1753\" height=\"1739\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png\" class=\"attachment-full size-full\" alt=\"Graphic of an ice skate\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png 1753w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-300x298.png 300w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1024x1016.png 1024w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-150x150.png 150w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-768x762.png 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1536x1524.png 1536w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-64x64.png 64w\" sizes=\"(max-width: 1753px) 100vw, 1753px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/gb.png\" alt=\"United Kingdom\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tBethany Frisby\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited Kingdom\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Haury_Gwen_2022-scaled.jpg\" class=\"attachment-full size-full\" alt=\"gwenaelle haury\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Haury_Gwen_2022-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Haury_Gwen_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Haury_Gwen_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Haury_Gwen_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Haury_Gwen_2022-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Haury_Gwen_2022-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Haury_Gwen_2022-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/fr.png\" alt=\"France\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tGwen Haury\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tFrance\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1753\" height=\"1739\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png\" class=\"attachment-full size-full\" alt=\"Graphic of an ice skate\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png 1753w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-300x298.png 300w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1024x1016.png 1024w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-150x150.png 150w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-768x762.png 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1536x1524.png 1536w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-64x64.png 64w\" sizes=\"(max-width: 1753px) 100vw, 1753px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/ua.png\" alt=\"Ukraine\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tMykyta Husakov\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUkraine\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Jensen_Maren_2023-scaled.jpg\" class=\"attachment-full size-full\" alt=\"Maren Jensen\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Jensen_Maren_2023-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Jensen_Maren_2023-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Jensen_Maren_2023-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Jensen_Maren_2023-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Jensen_Maren_2023-1600x2000.jpg 1600w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Jensen_Maren_2023-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Jensen_Maren_2023-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Jensen_Maren_2023-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/us.png\" alt=\"United States\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tMaren Jensen\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited States\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1753\" height=\"1739\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png\" class=\"attachment-full size-full\" alt=\"Graphic of an ice skate\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png 1753w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-300x298.png 300w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1024x1016.png 1024w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-150x150.png 150w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-768x762.png 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1536x1524.png 1536w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-64x64.png 64w\" sizes=\"(max-width: 1753px) 100vw, 1753px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/gb.png\" alt=\"United Kingdom\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tJennifer Kerr\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited Kingdom\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1000\" height=\"1250\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Kershaw_Matt_2022.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Kershaw_Matt_2022.jpg 1000w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Kershaw_Matt_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Kershaw_Matt_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Kershaw_Matt_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Kershaw_Matt_2022-51x64.jpg 51w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/gb.png\" alt=\"United Kingdom\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tMatthew Kershaw\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited Kingdom\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1000\" height=\"1250\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Konik_Vika_2022_0.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Konik_Vika_2022_0.jpg 1000w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Konik_Vika_2022_0-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Konik_Vika_2022_0-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Konik_Vika_2022_0-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Konik_Vika_2022_0-51x64.jpg 51w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/ua.png\" alt=\"Ukraine\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tVika Konik\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUkraine\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Lowell_Garrett_2022-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Lowell_Garrett_2022-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Lowell_Garrett_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Lowell_Garrett_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Lowell_Garrett_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Lowell_Garrett_2022-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Lowell_Garrett_2022-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Lowell_Garrett_2022-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/us.png\" alt=\"United States\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tGarrett Lowell\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited States\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Lyon_Emily_2023-scaled.jpg\" class=\"attachment-full size-full\" alt=\"emily lyon\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Lyon_Emily_2023-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Lyon_Emily_2023-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Lyon_Emily_2023-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Lyon_Emily_2023-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Lyon_Emily_2023-1600x2000.jpg 1600w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Lyon_Emily_2023-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Lyon_Emily_2023-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2024\/07\/Lyon_Emily_2023-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/us.png\" alt=\"United States\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tEmily Lyon\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited States\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1000\" height=\"1250\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Muth_Sophie-Estelle_2022_0.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Muth_Sophie-Estelle_2022_0.jpg 1000w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Muth_Sophie-Estelle_2022_0-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Muth_Sophie-Estelle_2022_0-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Muth_Sophie-Estelle_2022_0-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Muth_Sophie-Estelle_2022_0-51x64.jpg 51w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/de.png\" alt=\"Germany\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tSophie Muth\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tGermany\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Nyqvist_Wilma_2022-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Nyqvist_Wilma_2022-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Nyqvist_Wilma_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Nyqvist_Wilma_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Nyqvist_Wilma_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Nyqvist_Wilma_2022-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Nyqvist_Wilma_2022-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Nyqvist_Wilma_2022-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/se.png\" alt=\"Sweden\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tWilma Nyqvist\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tSweden\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1000\" height=\"1250\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Ojala_Kevin_2022_0.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Ojala_Kevin_2022_0.jpg 1000w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Ojala_Kevin_2022_0-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Ojala_Kevin_2022_0-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Ojala_Kevin_2022_0-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Ojala_Kevin_2022_0-51x64.jpg 51w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/ee.png\" alt=\"Estonia\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tKevin Ojala\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tEstonia\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1753\" height=\"1739\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png\" class=\"attachment-full size-full\" alt=\"Graphic of an ice skate\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png 1753w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-300x298.png 300w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1024x1016.png 1024w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-150x150.png 150w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-768x762.png 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1536x1524.png 1536w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-64x64.png 64w\" sizes=\"(max-width: 1753px) 100vw, 1753px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/fr.png\" alt=\"France\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tPeroline Ojardias\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tFrance\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1753\" height=\"1739\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png\" class=\"attachment-full size-full\" alt=\"Graphic of an ice skate\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png 1753w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-300x298.png 300w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1024x1016.png 1024w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-150x150.png 150w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-768x762.png 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1536x1524.png 1536w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-64x64.png 64w\" sizes=\"(max-width: 1753px) 100vw, 1753px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/fi.png\" alt=\"Finland\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tWarttu Riihim\u04d3ki\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tFinland\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1753\" height=\"1739\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png\" class=\"attachment-full size-full\" alt=\"Graphic of an ice skate\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png 1753w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-300x298.png 300w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1024x1016.png 1024w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-150x150.png 150w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-768x762.png 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1536x1524.png 1536w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-64x64.png 64w\" sizes=\"(max-width: 1753px) 100vw, 1753px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/se.png\" alt=\"Sweden\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tSarah Rosvall\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tSweden\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"2560\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Ruokonen_Enja_2022-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Ruokonen_Enja_2022-scaled.jpg 2048w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Ruokonen_Enja_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Ruokonen_Enja_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Ruokonen_Enja_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Ruokonen_Enja_2022-1229x1536.jpg 1229w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Ruokonen_Enja_2022-1638x2048.jpg 1638w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Ruokonen_Enja_2022-51x64.jpg 51w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/fi.png\" alt=\"Finland\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tEnja Ruokonen\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tFinland\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1000\" height=\"1250\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Saccinto_Pablo_2022.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Saccinto_Pablo_2022.jpg 1000w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Saccinto_Pablo_2022-240x300.jpg 240w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Saccinto_Pablo_2022-819x1024.jpg 819w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Saccinto_Pablo_2022-768x960.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Saccinto_Pablo_2022-51x64.jpg 51w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/ar.png\" alt=\"Argentina\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tPablo Saccinto\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tArgentina\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1980\" height=\"2018\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/09\/Sanchez_Alicia_2018_rs.jpg\" class=\"attachment-full size-full\" alt=\"Alicia Sanchez\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/09\/Sanchez_Alicia_2018_rs.jpg 1980w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/09\/Sanchez_Alicia_2018_rs-294x300.jpg 294w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/09\/Sanchez_Alicia_2018_rs-1005x1024.jpg 1005w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/09\/Sanchez_Alicia_2018_rs-768x783.jpg 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/09\/Sanchez_Alicia_2018_rs-1600x1631.jpg 1600w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/09\/Sanchez_Alicia_2018_rs-1507x1536.jpg 1507w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/09\/Sanchez_Alicia_2018_rs-64x64.jpg 64w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/mx.png\" alt=\"Mexico\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tAlicia Sanchez del la Fuente\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tMexico\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1753\" height=\"1739\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png\" class=\"attachment-full size-full\" alt=\"Graphic of an ice skate\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png 1753w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-300x298.png 300w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1024x1016.png 1024w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-150x150.png 150w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-768x762.png 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1536x1524.png 1536w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-64x64.png 64w\" sizes=\"(max-width: 1753px) 100vw, 1753px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/us.png\" alt=\"United States\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tAiden Schoeffler\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited States\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1753\" height=\"1739\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png\" class=\"attachment-full size-full\" alt=\"Graphic of an ice skate\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png 1753w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-300x298.png 300w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1024x1016.png 1024w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-150x150.png 150w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-768x762.png 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1536x1524.png 1536w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-64x64.png 64w\" sizes=\"(max-width: 1753px) 100vw, 1753px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/us.png\" alt=\"United States\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tAaliyah Sekihara\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited States\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1753\" height=\"1739\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png\" class=\"attachment-full size-full\" alt=\"Graphic of an ice skate\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png 1753w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-300x298.png 300w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1024x1016.png 1024w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-150x150.png 150w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-768x762.png 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1536x1524.png 1536w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-64x64.png 64w\" sizes=\"(max-width: 1753px) 100vw, 1753px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/us.png\" alt=\"United States\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tKatie Sekihara\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited States\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t<div class=\"item-photo\">\n\t\t\t\t\t\t<div class=\"photo-cover\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1753\" height=\"1739\" src=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png\" class=\"attachment-full size-full\" alt=\"Graphic of an ice skate\" decoding=\"async\" srcset=\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0.png 1753w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-300x298.png 300w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1024x1016.png 1024w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-150x150.png 150w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-768x762.png 768w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-1536x1524.png 1536w, https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/07\/22249901-DOI-Cast_Page-No_Headshot_Generic_Image_0-64x64.png 64w\" sizes=\"(max-width: 1753px) 100vw, 1753px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icon-country\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.disneyonice.com\/wp-content\/themes\/disneyonice\/dist\/img\/flags\/us.png\" alt=\"United States\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-name\">\n\t\t\t\t\t\tJason Takahashi\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"item-country\">\n\t\t\t\t\t\tUnited States\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/section>\n<\/div>\n\n\n\n<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":0,"parent":14137,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cast and Crew | Princesses &amp; H\u00e9ros | The Official Site of Disney On Ice<\/title>\n<meta name=\"description\" content=\"Meet the cast of Disney On Ice presents Find Your Hero\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.disneyonice.com\/en-id\/princesses-heros\/cast\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cast and Crew | Princesses &amp; H\u00e9ros | The Official Site of Disney On Ice\" \/>\n<meta property=\"og:description\" content=\"Meet the cast of Disney On Ice presents Find Your Hero\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.disneyonice.com\/en-id\/princesses-heros\/cast\/\" \/>\n<meta property=\"og:site_name\" content=\"The Official Site of Disney On Ice\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T13:22:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.disneyonice.com\/sr-rs\/princesses-heros\/cast\/\",\"url\":\"https:\/\/www.disneyonice.com\/sr-rs\/princesses-heros\/cast\/\",\"name\":\"Cast and Crew | Princesses & H\u00e9ros | The Official Site of Disney On Ice\",\"isPartOf\":{\"@id\":\"https:\/\/www.disneyonice.com\/es-cl\/#website\"},\"datePublished\":\"2025-02-24T17:25:36+00:00\",\"dateModified\":\"2025-02-25T13:22:23+00:00\",\"description\":\"Meet the cast of Disney On Ice presents Find Your Hero\",\"breadcrumb\":{\"@id\":\"https:\/\/www.disneyonice.com\/sr-rs\/princesses-heros\/cast\/#breadcrumb\"},\"inLanguage\":\"en-ID\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.disneyonice.com\/sr-rs\/princesses-heros\/cast\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.disneyonice.com\/sr-rs\/princesses-heros\/cast\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.disneyonice.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Princesses &amp; H\u00e9ros\",\"item\":\"https:\/\/www.disneyonice.com\/es-do\/princesses-heros\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cast\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.disneyonice.com\/es-cl\/#website\",\"url\":\"https:\/\/www.disneyonice.com\/es-cl\/\",\"name\":\"The Official Site of Disney On Ice\",\"description\":\"A series of touring ice shows produced by Feld Entertainment under agreement with The Walt Disney Company.\",\"publisher\":{\"@id\":\"https:\/\/www.disneyonice.com\/es-cl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.disneyonice.com\/es-cl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-ID\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.disneyonice.com\/es-cl\/#organization\",\"name\":\"Disney On Ice\",\"url\":\"https:\/\/www.disneyonice.com\/es-cl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-ID\",\"@id\":\"https:\/\/www.disneyonice.com\/es-cl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Disney-Check.png\",\"contentUrl\":\"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Disney-Check.png\",\"width\":100,\"height\":104,\"caption\":\"Disney On Ice\"},\"image\":{\"@id\":\"https:\/\/www.disneyonice.com\/es-cl\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cast and Crew | Princesses & H\u00e9ros | The Official Site of Disney On Ice","description":"Meet the cast of Disney On Ice presents Find Your Hero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.disneyonice.com\/en-id\/princesses-heros\/cast\/","og_locale":"en_US","og_type":"article","og_title":"Cast and Crew | Princesses & H\u00e9ros | The Official Site of Disney On Ice","og_description":"Meet the cast of Disney On Ice presents Find Your Hero","og_url":"https:\/\/www.disneyonice.com\/en-id\/princesses-heros\/cast\/","og_site_name":"The Official Site of Disney On Ice","article_modified_time":"2025-02-25T13:22:23+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.disneyonice.com\/sr-rs\/princesses-heros\/cast\/","url":"https:\/\/www.disneyonice.com\/sr-rs\/princesses-heros\/cast\/","name":"Cast and Crew | Princesses & H\u00e9ros | The Official Site of Disney On Ice","isPartOf":{"@id":"https:\/\/www.disneyonice.com\/es-cl\/#website"},"datePublished":"2025-02-24T17:25:36+00:00","dateModified":"2025-02-25T13:22:23+00:00","description":"Meet the cast of Disney On Ice presents Find Your Hero","breadcrumb":{"@id":"https:\/\/www.disneyonice.com\/sr-rs\/princesses-heros\/cast\/#breadcrumb"},"inLanguage":"en-ID","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.disneyonice.com\/sr-rs\/princesses-heros\/cast\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.disneyonice.com\/sr-rs\/princesses-heros\/cast\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.disneyonice.com\/"},{"@type":"ListItem","position":2,"name":"Princesses &amp; H\u00e9ros","item":"https:\/\/www.disneyonice.com\/es-do\/princesses-heros\/"},{"@type":"ListItem","position":3,"name":"Cast"}]},{"@type":"WebSite","@id":"https:\/\/www.disneyonice.com\/es-cl\/#website","url":"https:\/\/www.disneyonice.com\/es-cl\/","name":"The Official Site of Disney On Ice","description":"A series of touring ice shows produced by Feld Entertainment under agreement with The Walt Disney Company.","publisher":{"@id":"https:\/\/www.disneyonice.com\/es-cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.disneyonice.com\/es-cl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-ID"},{"@type":"Organization","@id":"https:\/\/www.disneyonice.com\/es-cl\/#organization","name":"Disney On Ice","url":"https:\/\/www.disneyonice.com\/es-cl\/","logo":{"@type":"ImageObject","inLanguage":"en-ID","@id":"https:\/\/www.disneyonice.com\/es-cl\/#\/schema\/logo\/image\/","url":"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Disney-Check.png","contentUrl":"https:\/\/www.disneyonice.com\/wp-content\/uploads\/2023\/08\/Disney-Check.png","width":100,"height":104,"caption":"Disney On Ice"},"image":{"@id":"https:\/\/www.disneyonice.com\/es-cl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.disneyonice.com\/en-id\/wp-json\/wp\/v2\/pages\/14142"}],"collection":[{"href":"https:\/\/www.disneyonice.com\/en-id\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.disneyonice.com\/en-id\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.disneyonice.com\/en-id\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.disneyonice.com\/en-id\/wp-json\/wp\/v2\/comments?post=14142"}],"version-history":[{"count":5,"href":"https:\/\/www.disneyonice.com\/en-id\/wp-json\/wp\/v2\/pages\/14142\/revisions"}],"predecessor-version":[{"id":14166,"href":"https:\/\/www.disneyonice.com\/en-id\/wp-json\/wp\/v2\/pages\/14142\/revisions\/14166"}],"up":[{"embeddable":true,"href":"https:\/\/www.disneyonice.com\/en-id\/wp-json\/wp\/v2\/pages\/14137"}],"wp:attachment":[{"href":"https:\/\/www.disneyonice.com\/en-id\/wp-json\/wp\/v2\/media?parent=14142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}